{"id":2232,"date":"2012-09-04T20:15:27","date_gmt":"2012-09-04T20:15:27","guid":{"rendered":"http:\/\/anistiapolitica.org.br\/abap3\/2012\/09\/04\/comissao-de-anistia-lanca-livro-sobre-a-vala-de-perus-2\/"},"modified":"2012-09-04T20:15:27","modified_gmt":"2012-09-04T20:15:27","slug":"comissao-de-anistia-lanca-livro-sobre-a-vala-de-perus-2","status":"publish","type":"post","link":"http:\/\/anistiapolitica.org.br\/abap3\/2012\/09\/04\/comissao-de-anistia-lanca-livro-sobre-a-vala-de-perus-2\/","title":{"rendered":"Comiss\u00e3o de Anistia lan\u00e7a livro sobre a Vala de Perus"},"content":{"rendered":"<p \/>\n<p class=\"p1\" style=\"text-align: justify;\" \/>A Comiss\u00e3o de Anistia do Minist\u00e9rio da Justi\u00e7a e o Instituto Macuco lan\u00e7am nesta ter\u00e7a-feira (4\/10) o livro Vala Clandestina de Perus \u2013 Desaparecidos pol\u00edticos: um cap\u00edtulo n\u00e3o encerrado da hist\u00f3ria brasileira. A vala clandestina fica localizada no Cemit\u00e9rio Dom Bosco em Perus, na capital S\u00e3o Paulo, onde foram enterrados mais de mil corpos, incluindo de presos e desaparecidos pol\u00edticos.  <!--more-->  <\/p>\n<p class=\"p1\" style=\"text-align: justify;\">O lan\u00e7amento da publica\u00e7\u00e3o \u00e9 resultado de um projeto do Instituto Macuco selecionado pela segunda chamada p\u00fablica do projeto Marcas da Mem\u00f3ria, da Comiss\u00e3o de Anistia do Minist\u00e9rio da Justi\u00e7a divulgada em 2011.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">A obra com 200 p\u00e1ginas e fotos coloridas re\u00fane textos da ex-prefeita Luiza Erundina, que governava S\u00e3o Paulo \u00e0 \u00e9poca da descoberta da Vala de Perus; do vereador \u00cdtalo Cardoso e da ex-vereadoraTereza Lajolo, que fizeram parte da CPI da C\u00e2mara Municipal de S\u00e3o Paulo que investigou o caso (setembro de 1990 a\u00a0 maio de 1991); de Ivan Seixas, Maria Am\u00e9lia Teles e Suzana Lisboa, da Comiss\u00e3o de Familiares de Mortos e Desaparecidos Pol\u00edticos,\u00a0 al\u00e9m de Paulo Abr\u00e3o, presidente da Comiss\u00e3o de Anistia. Na d\u00e9cada de 1990, a CPI do legislativo paulistano ouviu v\u00edtimas e c\u00famplices do regime, localizou corpos, e um centro de tortura at\u00e9 ent\u00e3o desconhecido.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Junto ao lan\u00e7amento da publica\u00e7\u00e3o, haver\u00e1 exposi\u00e7\u00e3o com fotos hist\u00f3ricas registradas pelo fot\u00f3grafo Marcelo Vigneron durante a abertura da Vala de Perus. A exposi\u00e7\u00e3o re\u00fane ainda imagens encontradas em diversos arquivos de familiares de presos e desaparecidos pol\u00edticos.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Marcas da Mem\u00f3ria \u2013 A iniciativa da Comiss\u00e3o da Anistia do Minist\u00e9rio da Justi\u00e7a seleciona projetos de preserva\u00e7\u00e3o, divulga\u00e7\u00e3o e forma\u00e7\u00e3o da mem\u00f3ria da Anistia Pol\u00edtica e do processo de Justi\u00e7a de Transi\u00e7\u00e3o no Brasil. Este ano, a III Chamada P\u00fablica do Marcas da Mem\u00f3ria oferecer\u00e1 apoio financeiro de R$ 30 mil a R$ 600 mil para os projetos selecionados, que foram enviados entre maio e junho passado.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><strong>Servi\u00e7o<\/strong><\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Data: ter\u00e7a-feira (4 de setembro de 2012)<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Hor\u00e1rio: 19h<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Local: Funda\u00e7\u00e3o Escola de Sociologia e Pol\u00edtica de S\u00e3o Paulo (Rua General Jardim, 522, Vila Buarque, S\u00e3o Paulo- SP)<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><strong>Mais informa\u00e7\u00f5es:<\/strong><\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Assessoria de Comunica\u00e7\u00e3o Social \u2013 Minist\u00e9rio da Justi\u00e7a<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Carolina Valadares<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Telefone: (61) 2025 3135\/3315<\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><a href=\"mailto:carolina.valadares@mj.gov.br\">carolina.valadares@mj.gov.br<\/a><\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><a href=\"http:\/\/www.mj.gov.br\/\">www.mj.gov.br<\/a><\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><a href=\"http:\/\/blog.justica.gov.br\/\">http:\/\/blog.justica.gov.br<\/a><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o de Anistia do Minist\u00e9rio da Justi\u00e7a e o Instituto Macuco lan\u00e7am nesta ter\u00e7a-feira (4\/10) o livro Vala Clandestina de Perus \u2013 Desaparecidos pol\u00edticos: um cap\u00edtulo n\u00e3o encerrado da hist\u00f3ria brasileira. A vala clandestina fica localizada no Cemit\u00e9rio Dom Bosco em Perus, na capital S\u00e3o Paulo, onde foram enterrados mais de mil corpos, incluindo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/posts\/2232"}],"collection":[{"href":"http:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/comments?post=2232"}],"version-history":[{"count":0,"href":"http:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/posts\/2232\/revisions"}],"wp:attachment":[{"href":"http:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/media?parent=2232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/categories?post=2232"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/tags?post=2232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}