{"id":4362,"date":"2013-03-28T03:44:16","date_gmt":"2013-03-28T03:44:16","guid":{"rendered":"http:\/\/anistiapolitica.org.br\/abap3\/2013\/03\/28\/cnv-e-comissao-rubens-paiva-relembram-luta-das-mulheres-contra-a-ditadura\/"},"modified":"2013-03-28T03:44:16","modified_gmt":"2013-03-28T03:44:16","slug":"cnv-e-comissao-rubens-paiva-relembram-luta-das-mulheres-contra-a-ditadura","status":"publish","type":"post","link":"https:\/\/anistiapolitica.org.br\/abap3\/2013\/03\/28\/cnv-e-comissao-rubens-paiva-relembram-luta-das-mulheres-contra-a-ditadura\/","title":{"rendered":"CNV e Comiss\u00e3o Rubens Paiva relembram luta das mulheres contra a ditadura"},"content":{"rendered":"<p><p class=\"p1\" style=\"text-align: justify;\">Durante evento, participantes homenagearam In\u00eas Etienne Romeu, ex-presa pol\u00edtica e \u00fanica sobrevivente da Casa da Morte de Petr\u00f3polis<\/p>\n<p class=\"p1\" style=\"text-align: justify;\" \/>A Comiss\u00e3o Nacional da Verdade e a Comiss\u00e3o Estadual da Verdade Rubens Paiva realizaram na noite de ontem, em S\u00e3o Paulo, a Audi\u00eancia P\u00fablica &#8220;Verdade e G\u00eanero&#8221;, para discutir e relembrar a luta das mulheres na resist\u00eancia \u00e0 ditadura de 64 e as viol\u00eancias \u00e0s quais elas foram submetidas neste per\u00edodo.  <!--more-->  <\/p>\n<p class=\"p1\" style=\"text-align: justify;\">A ministra Eleonora Menicucci, da Secretaria de Pol\u00edticas para Mulheres da Presid\u00eancia da Rep\u00fablica, comp\u00f4s a mesa da audi\u00eancia junto com o coordenador da Comiss\u00e3o Nacional da Verdade, Paulo S\u00e9rgio Pinheiro, e com o presidente da Comiss\u00e3o Estadual da Verdade Rubens Paiva (SP), deputado Adriano Diogo.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Eleonora Menicucci ressaltou que &#8220;as mulheres precisam ser redescobertas na hist\u00f3ria da luta contra a ditadura. N\u00e3o se recupera a mem\u00f3ria se n\u00e3o se recupera a hist\u00f3ria das mulheres que fizeram parte e que tamb\u00e9m constru\u00edram essa hist\u00f3ria.&#8221; Mais de 50 mulheres foram mortas ou ainda est\u00e3o desaparecidas em consequ\u00eancia da luta pol\u00edtica de resist\u00eancia ao regime militar de 64.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Durante a cerim\u00f4nia, a ex-presa pol\u00edtica Am\u00e9lia Teles relatou as torturas que ela e os filhos sofreram durante o per\u00edodo em que ela esteve presa. Disse que os torturadores usavam da desigualdade de g\u00eanero para torturar ainda mais as mulheres presas pelo regime. &#8220;Eles usavam a maternidade contra n\u00f3s, torturavam nossos filhos e diziam que iam mat\u00e1-los&#8221;, explicou Am\u00e9lia.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Muito emocionada, tamb\u00e9m relatou casos de viol\u00eancia sexual praticados por agentes da repress\u00e3o contra ela nas depend\u00eancias do pres\u00eddio feminino em S\u00e3o Paulo. Destacou que durante muito tempo as mulheres n\u00e3o conseguiam falar sobre esse tipo de tortura. Para Am\u00e9lia, &#8220;\u00e9 um peso muito grande falar da viol\u00eancia sexual. Voc\u00ea fica estigmatizada.&#8221;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">O p\u00fablico ouviu emocionado o testemunho de Am\u00e9lia e, logo em seguida, a homenagem da ministra Eleonora Menicucci, tamb\u00e9m ex-presa pol\u00edtica, a In\u00eas Etienne Romeu, \u00fanica sobrevivente da Casa da Morte de Petr\u00f3polis.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">In\u00eas Etenne revelou, em um depoimento dado \u00e0 OAB em 71, as torturas e viol\u00eancia sexuais que havia sofrido no cativeiro, e conseguiu dar informa\u00e7\u00f5es suficientes para que o local fosse identificado anos mais tarde. Eleonora Menicucci destacou a coragem de In\u00eas ao falar dos atos cometidos contra ela. &#8220;Falar sobre viol\u00eancia sexual \u00e9 desnudar-se. A In\u00eas, ao desnudar-se entregou a toda a sociedade brasileira a exist\u00eancia da Casa da Morte.&#8221;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">O coordenador da Comiss\u00e3o Nacional da Verdade, Paulo S\u00e9rgio Pinheiro, agradeceu \u00e0s mulheres que lutaram contra o regime ditatorial brasileiro. Destacou tamb\u00e9m que a CNV se preocupou desde o seu in\u00edcio em buscar a hist\u00f3ria e resgatar a mem\u00f3ria da atua\u00e7\u00e3o dessas mulheres. A CNV criou no final do ano passado o GT Ditadura e G\u00eanero para pesquisar a viol\u00eancia contra a mulher, suas consequ\u00eancias e impactos.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Paulo S\u00e9rgio Pinheiro destacou que o relat\u00f3rio que ser\u00e1 entregue ao Governo brasileiro ao final do mandato da Comiss\u00e3o em maio de 2014 ir\u00e1 &#8220;considerar fortemente a situa\u00e7\u00e3o das mulheres&#8221;. E completou : &#8220;\u00c9 por causa da persist\u00eancia da viol\u00eancia, estatal ou n\u00e3o, contra a mulher, que precisamos lidar com essa quest\u00e3o.&#8221;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Integrantes da CNV Rosa Cardoso e Maria Rita Kehl tamb\u00e9m participaram da cerim\u00f4nia. Estiveram na segunda mesa de debates com a doutora em teologia e filosofia e especialista em g\u00eanero Ivone Gebara. Ivone falou sobre a rela\u00e7\u00e3o entre o poder e a viol\u00eancia contra a mulher, durante o per\u00edodo da repress\u00e3o e at\u00e9 os dias de hoje. Ela destacou que, al\u00e9m da viol\u00eancia por militarem contra o regime autorit\u00e1rio, as mulheres tamb\u00e9m apanhavam pela rebeldia de se envolverem em um espa\u00e7o dito masculino, o espa\u00e7o de luta, o espa\u00e7o de combate.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><strong>SOBREVIVENTE &#8211; <\/strong>Em 1971, In\u00eas foi presa na cidade de S\u00e3o Paulo pela equipe do delegado Fleury. Levada para Petr\u00f3polis ficou presa ilegalmente por mais de tr\u00eas meses, per\u00edodo em que sofreu diversos tipos de tortura, incluindo a viol\u00eancia sexual. In\u00eas conseguiu sair da Casa da Morte depois de ter convencido os agentes da repress\u00e3o de que iria trabalhar como informante do Centro de Informa\u00e7\u00f5es do Ex\u00e9rcito (CIE). Quando liberada, In\u00eas n\u00e3o seguiu as ordens dos torturadores.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Passou a ser perseguida novamente e, ao dar entrada em um hospital para tratar das les\u00f5es consequentes dos meses de tortura, foi presa e levada para a penitenci\u00e1ria de Bangu, no Rio de Janeiro, onde ficou presa por mais oito anos.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">O depoimento dado por In\u00eas ap\u00f3s a Lei da Anistia de 1979 foi fundamental para identificar a casa que era usada como cativeiro clandestino em Petr\u00f3polis. Durante o tempo em que ficou sob poder dos agentes da repress\u00e3o, In\u00eas conseguiu escutar e memorizar os codinomes de seus algozes, bem como o codinome do m\u00e9dico que a atendia ap\u00f3s as sess\u00f5es de tortura, o ex-militar Am\u00edlcar Lobo, que usava o codinome de &#8220;doutor Carneiro&#8221;.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">In\u00eas tamb\u00e9m se lembrou dos nomes de outros presos pol\u00edticos que passaram, sem registro, pela Casa da Morte de Petr\u00f3polis. Mas a informa\u00e7\u00e3o que determinou a descoberta posterior da propriedade usada como cativeiro clandestino foi um n\u00famero de telefone que In\u00eas conseguiu ouvir durante uma conversa entre dois agentes da repress\u00e3o. Foi gra\u00e7as \u00e0 coragem de In\u00eas Etienne que foi poss\u00edvel localizar o local clandestino de tortura e os nomes de alguns presos pol\u00edticos que l\u00e1 morreram sem nenhum tipo de registro formal.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Em 2003, In\u00eas sofreu um acidente que a deixou com sequelas, como dificuldade na fala e problemas de mem\u00f3ria. Em 2009 recebeu o pr\u00eamio de Direitos Humanos &#8220;Direito \u00e0 Mem\u00f3ria e \u00e0 Verdade&#8221;, do Minist\u00e9rio da Justi\u00e7a.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Fonte &#8211; Comiss\u00e3o Nacional da Verdade &#8211;\u00a0<span style=\"line-height: 1.3em;\">Assessoria de Comunica\u00e7\u00e3o<\/span><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante evento, participantes homenagearam In\u00eas Etienne Romeu, ex-presa pol\u00edtica e \u00fanica sobrevivente da Casa da Morte de Petr\u00f3polis A Comiss\u00e3o Nacional da Verdade e a Comiss\u00e3o Estadual da Verdade Rubens Paiva realizaram na noite de ontem, em S\u00e3o Paulo, a Audi\u00eancia P\u00fablica &#8220;Verdade e G\u00eanero&#8221;, para discutir e relembrar a luta das mulheres na resist\u00eancia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/posts\/4362"}],"collection":[{"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/comments?post=4362"}],"version-history":[{"count":0,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/posts\/4362\/revisions"}],"wp:attachment":[{"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/media?parent=4362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/categories?post=4362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/tags?post=4362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}