{"id":4363,"date":"2013-03-28T14:08:03","date_gmt":"2013-03-28T14:08:03","guid":{"rendered":"http:\/\/anistiapolitica.org.br\/abap3\/2013\/03\/28\/espirito-santo-e-o-decimo-estado-a-instituir-comissao-da-verdade\/"},"modified":"2013-03-28T14:08:03","modified_gmt":"2013-03-28T14:08:03","slug":"espirito-santo-e-o-decimo-estado-a-instituir-comissao-da-verdade","status":"publish","type":"post","link":"https:\/\/anistiapolitica.org.br\/abap3\/2013\/03\/28\/espirito-santo-e-o-decimo-estado-a-instituir-comissao-da-verdade\/","title":{"rendered":"Esp\u00edrito Santo \u00e9 o d\u00e9cimo estado a instituir Comiss\u00e3o da Verdade"},"content":{"rendered":"<p><p class=\"p1\" style=\"text-align: justify;\">Grupo ainda precisa ter os nomes de seus membros anunciados pelo governador<\/p>\n<p class=\"p2\" style=\"text-align: justify;\" \/>Foi instalada dia 25 a Comiss\u00e3o Estadual da Verdade do Esp\u00edrito Santo. O decreto da instala\u00e7\u00e3o da Comiss\u00e3o foi assinado pelo governador Renato Casagrande (PSB), no Pal\u00e1cio Anchieta, em Vit\u00f3ria. A ministra da Secretaria de Direitos Humanos da Presid\u00eancia da Rep\u00fablica (SDH-PR), Maria do Ros\u00e1rio, participou da cerim\u00f4nia, em que tamb\u00e9m foi assinado o decreto de cria\u00e7\u00e3o da Comiss\u00e3o Estadual para a erradica\u00e7\u00e3o do Trabalho Escravo (Coetrae).  <!--more-->  <\/p>\n<p class=\"p2\" style=\"text-align: justify;\">A Comiss\u00e3o da Verdade capixaba, a d\u00e9cima estadual, ter\u00e1 como fun\u00e7\u00e3o investigar casos de viola\u00e7\u00f5es aos direitos humanos que ocorreram durante a ditadura (1964-185).<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">Das 27 unidades da federa\u00e7\u00e3o, apenas S\u00e3o Paulo, Rio de Janeiro, Alagoas, Para\u00edba, Maranh\u00e3o, Pernambuco, Rio Grande do Sul, Santa Catarina e Paran\u00e1 j\u00e1 t\u00eam suas comiss\u00f5es criadas. A CNV, em outubro do ano passado, remeteu of\u00edcio a governadores do pa\u00eds solicitando o engajamento na cria\u00e7\u00e3o das comiss\u00f5es, juntamente com o apoio das assembleias legislativas. A ideia \u00e9 que as comiss\u00f5es estaduais ajam em parceria com a CNV, sancionada em novembro de 2011 pela presidenta Dilma Rousseff.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">A Lei 9.911, de cria\u00e7\u00e3o da comiss\u00e3o do Esp\u00edrito Santo, foi sancionada pelo governador em setembro do ano passado. A comiss\u00e3o ter\u00e1 por sete membros designados por ato do governador e funcionar\u00e1 pr dois anos, podendo ser prorrogada uma vez por igual per\u00edodo. Na ocasi\u00e3o, tamb\u00e9m foi anunciado o envio \u00e0 Assembleia Legislativa do projeto de lei que institui o Comit\u00ea e o Mecanismo Estadual para Preven\u00e7\u00e3o e Erradica\u00e7\u00e3o da Tortura, cujo objetivo \u00e9 fazer visitas regulares de monitoramento a todos os lugares de priva\u00e7\u00e3o de liberdade no estado, visando acabar com a pr\u00e1tica e prevenir penas cru\u00e9is e degradantes.<\/p>\n<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">Fonte &#8211; Rede Brasil Atual<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grupo ainda precisa ter os nomes de seus membros anunciados pelo governador Foi instalada dia 25 a Comiss\u00e3o Estadual da Verdade do Esp\u00edrito Santo. O decreto da instala\u00e7\u00e3o da Comiss\u00e3o foi assinado pelo governador Renato Casagrande (PSB), no Pal\u00e1cio Anchieta, em Vit\u00f3ria. A ministra da Secretaria de Direitos Humanos da Presid\u00eancia da Rep\u00fablica (SDH-PR), Maria [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/posts\/4363"}],"collection":[{"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/comments?post=4363"}],"version-history":[{"count":0,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/posts\/4363\/revisions"}],"wp:attachment":[{"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/media?parent=4363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/categories?post=4363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/tags?post=4363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}