{"id":6308,"date":"2013-08-15T00:23:14","date_gmt":"2013-08-15T00:23:14","guid":{"rendered":"http:\/\/anistiapolitica.org.br\/abap3\/2013\/08\/15\/caravana-da-anistia-homenagens-a-ex-presos-politicos\/"},"modified":"2013-08-15T00:23:14","modified_gmt":"2013-08-15T00:23:14","slug":"caravana-da-anistia-homenagens-a-ex-presos-politicos","status":"publish","type":"post","link":"https:\/\/anistiapolitica.org.br\/abap3\/2013\/08\/15\/caravana-da-anistia-homenagens-a-ex-presos-politicos\/","title":{"rendered":"Caravana da Anistia: homenagens a ex-presos pol\u00edticos"},"content":{"rendered":"<p class=\"p1\" style=\"text-align: justify;\">Na sess\u00e3o de abertura da Caranava da Anistia, que acontecer\u00e1 na sede da OAB-PR, em Curitiba, na sexta-feira,16, haver\u00e1 homenagens p\u00f3stumas a ex-presos pol\u00edticos e seus familiares, al\u00e9m de homenagem ao ex-prefeito de Curitiba, Maur\u00edcio Fruet, e ao ex-governador, Jos\u00e9 Richa, que lutaram pela redemocratiza\u00e7\u00e3o do pa\u00eds.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\" \/><span style=\"line-height: 1.3em;\" \/><strong \/>Veja alguns dos nomes que ser\u00e3o homenageados:  <!--more-->  <\/strong><\/span><\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">1. ALDO FERNANDES<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Juiz de Direito, preso por duas ocasi\u00f5es durante o per\u00edodo da ditadura militar, foi severamente prejudicado na sua vida profissional devido as suas posi\u00e7\u00f5es ideol\u00f3gicas divergentes ao regime . Teve seus direitos pol\u00edticos cassados, nos primeiros dias do novo regime, e foi aposentado compulsoriamente nos meses seguintes.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">2. AMILCAR GIGANTE<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Professor Adjunto de cl\u00ednica m\u00e9dica e diretor do Hospital das Cl\u00ednicas da UFPR. Pelo seu envolvimento em atividades pol\u00edticas, foi proibido de lecionar em 1969, em fun\u00e7\u00e3o do Ato Institucional n\u00b0 5. Com a anistia, em 1979, voltou \u00e0 doc\u00eancia, na Universidade Federal de Pelotas (UFPEL). A sua experi\u00eancia de taqu\u00edgrafo da Assembleia Legislativa do Paran\u00e1, profiss\u00e3o atrav\u00e9s da qual custeou os seus pr\u00f3prios estudos m\u00e9dicos, lhe ensinara que o homem pode mudar, sim, o seu destino. E Am\u00edlcar agigantou-se contra o seu destino de perseguido pol\u00edtico, ressurgindo brilhantemente em muitas de suas horas hist\u00f3ricas, quer como m\u00e9dico, quer como professor, quer como autor de livros, quer como Magn\u00edfico Reitor da Universidade Federal de Pelotas.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">3. ANIBAL ABBATE SOLEY<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Veio para Foz do Igua\u00e7u em 1959 como exilado pol\u00edtico do pa\u00eds vizinho, devido \u00e0 ditadura do general Alfredo Stroessner.Numa opera\u00e7\u00e3o rel\u00e2mpago a repress\u00e3o da ditadura civil-militar sequestrou em dezembro de 1974, An\u00edbal Abbatte Soley, Rodolfo Mongelos, Cesar Cabral e Alejandro Stumpfs. Os empres\u00e1rios paraguaios foram conduzidos at\u00e9 um s\u00edtio em Goi\u00e1s, onde foram barbaramente torturados. A opera\u00e7\u00e3o foi executada pelo Centro de Informa\u00e7\u00f5es do Ex\u00e9rcito envolvendo cerca de 20 homens fortemente armados e seis ve\u00edculos de modelos diferentes<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">4. ANTONIO DOS TREIS REIS DE OLIVEIRA<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Militante da A\u00e7\u00e3o Libertadora Nacional, foi estudante de Ci\u00eancias Econ\u00f4micas na Faculdade de Apucarana, no Paran\u00e1. Junto com Jos\u00e9 Id\u00e9sio Brianesi, tamb\u00e9m assassinado pela ditadura, produzia programas para a r\u00e1dio local. Foi indiciado por sua participa\u00e7\u00e3o no Congresso da Uni\u00e3o Nacional de Estudantes (UNE). Segundo den\u00fancia dos presos pol\u00edticos de S\u00e3o Paulo, em documento datado de mar\u00e7o de 1976, Ant\u00f4nio foi metralhado, juntamente com Alceri Maria Gomes da Silva no dia 10 de maio de 1970, em sua resid\u00eancia, no Tatuap\u00e9, S\u00e3o Paulo, por agentes da Opera\u00e7\u00e3o Bandeirantes (OBAN), chefiada pelo Capit\u00e3o Maur\u00edcio Lopes de Lima.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">5. DANIEL CARVALHO<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Irm\u00e3o de Joel Jos\u00e9 de Carvalho. Tamb\u00e9m foi preso pol\u00edtico, trocado pelo embaixador su\u00ed\u00e7o.Ligando-se \u00e0 VPR, Daniel e seu irm\u00e3o Joel v\u00e3o para a Argentina e tentam entrar clandestinamente no Brasil pela fronteira sul, no dia 11 de julho de 1974, juntamente com quatro outros camaradas da VPR: o sapateiro Jos\u00e9 Lavechia (55 anos); o argentino Enrique Ernesto Ruggia, estudante de Veterin\u00e1ria em Buenos Aires (18 anos); Onofre Pinto, ex-sargento do Ex\u00e9rcito brasileiro (37 anos); e Vitor Carlos Ramos, escultor (30 anos). Tratava-se no entanto de uma armadilha preparada por \u201ccachorros\u201d (militantes que haviam passado a trabalhar para a repress\u00e3o).Tinha 28 anos quando foi morto na chacina do Parque Nacional do Igua\u00e7u.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">6. ENRIQUE ERNESTO RUGGIA<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Com 18 anos, argentino estudante de Veterin\u00e1ria em Buenos Aires era o mais novo do grupo assassinado na Estrada do Colono junto com os irm\u00e3os Daniel e Joel Carvalho, o sapateiro Jos\u00e9 Lavechia (55 anos); Onofre Pinto, ex-sargento do Ex\u00e9rcito brasileiro (37 anos); e Vitor Carlos Ramos, escultor (30 anos). Tentam entrar clandestinamente no Brasil pela fronteira sul, no dia 11 de julho de 1974. Tratava-se no entanto de uma armadilha preparada por \u201ccachorros\u201d (militantes que haviam passado a trabalhar para a repress\u00e3o).<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">7. ILDEU MANSO VIEIRA<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Um dos l\u00edderes do PCB no Paran\u00e1, escreveu dois livros sobre seu per\u00edodo na pris\u00e3o. Seu filho, Ildeu Manso Vieira J\u00fanior, foi obrigado a presenciar as sev\u00edcias sofridas pelo pai, conforme este relatou na Auditoria Militar, em 1975.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">8. JOAQUIM PIRES CERVEIRA<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Foi preso em 1965 e encaminhado \u00e0 5\u00aa Regi\u00e3o Militar e entregue ao Coronel Fragomini. Em 29 de maio de 1967 foi absolvido pelo Conselho Especial de Justi\u00e7a da 5\u00aa Auditoria, da den\u00fancia do processo 324, por crime de subvers\u00e3o. Foi preso novamente, em 1970, com sua mulher e o filho, que foram torturados no DOI-CODI\/RJ.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Banido do pa\u00eds em junho de 1970, quando do sequestro do embaixador da Alemanha no Brasil, viajando para a Arg\u00e9lia com outros 39 presos pol\u00edticos. Preso em Buenos Aires em 11 de dezembro de 1973, juntamente com Jo\u00e3o Batista Rita, por policiais brasileiros, provavelmente comandados pelo delegado S\u00e9rgio Fleury.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Ambos foram vistos por alguns presos pol\u00edticos no DOI-CODI-RJ quando chegavam trazidos por uma ambul\u00e2ncia. Estavam amarrados juntos, em posi\u00e7\u00e3o fetal, tendo os rostos inchados, esburacados e repletos de sangue na cabe\u00e7a. O arquivo do DOPS\/PR, o nome do major Cerveira foi encontrado numa gaveta com a identifica\u00e7\u00e3o \u201cfalecidos\u201d.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">9. JOEL JOS\u00c9 DE CARVALHO<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Iniciou sua milit\u00e2ncia pol\u00edtica no Partido Comunista Brasileiro. Depois do golpe militar de 1964, passou a atuar no PC do B. Integrou a Ala Vermelha, o Movimento Revolucion\u00e1rio Tiradentes e a VPR. Foi um dos 70 presos pol\u00edticos trocados pelo embaixador su\u00ed\u00e7o Giovanni Bucher, sequestrado pela VPR em 1971.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Ligando-se \u00e0 VPR, Joel e seu irm\u00e3o Daniel v\u00e3o para a Argentina e tentam entrar clandestinamente no Brasil pela fronteira sul, no dia 11 de julho de 1974, juntamente com quatro outros camaradas da VPR: o sapateiro Jos\u00e9 Lavechia (55 anos); o argentino Enrique Ernesto Ruggia, estudante de Veterin\u00e1ria em Buenos Aires (18 anos); Onofre Pinto, ex-sargento do Ex\u00e9rcito brasileiro (37 anos); e Vitor Carlos Ramos, escultor (30 anos). Tratava-se no entanto de uma armadilha preparada por \u201ccachorros\u201d (militantes que haviam passado a trabalhar para a repress\u00e3o).Morreu aos 26 anos, na chacina do Parque Nacional de Igua\u00e7u.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">10. JOS\u00c9 ID\u00c9SIO BRIANEZI<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Estudante da Escola T\u00e9cnica de Com\u00e9rcio de Apucarana inicia sua milit\u00e2ncia pol\u00edtica na Uni\u00e3o dos Estudantes de Apucarana (UEA) no ano de 1966. Em 1968, passa a integrar a dissid\u00eancia do PCB (Partido Comunista Brasileiro) em Apucarana.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Com a invas\u00e3o e o fechamento da UEA em dezembro de 1968 pelo regime militar, torna-se insustent\u00e1vel a sua perman\u00eancia na cidade. Muda-se para S\u00e3o Paulo, para se integrar \u00e0 ALN (A\u00e7\u00e3o Libertadora Nacional), juntamente com Ant\u00f4nio dos Tr\u00eas Reis de Oliveira. Documentos dos \u00f3rg\u00e3os de seguran\u00e7a registram que ele seria um dos subcomandantes do Grupo T\u00e1tico Armado da ALN, em S\u00e3o Paulo, no in\u00edcio de 1970.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Nesse mesmo ano, foi morto por agentes da Opera\u00e7\u00e3o Bandeirantes (OBAN). Sua certid\u00e3o de \u00f3bito traz a vers\u00e3o oficial de que faleceu em 13 de mar\u00e7o de 1970, na pens\u00e3o onde morava, no Campo Belo, capital paulista, em tiroteio. An\u00e1lise pericial dos documentos existentes e de uma foto encontrada no arquivo do DOPS, leva a Comiss\u00e3o Especial sobre Mortos e Desaparecidos Pol\u00edticos a concluir que Jos\u00e9 Id\u00e9sio foi executado sumariamente, tendo levado tr\u00eas tiros de frente para tr\u00e1s, com evidente diferen\u00e7a de n\u00edvel entre o corpo e os autores dos disparos.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">11. JOS\u00c9 LAV\u00c9CHIA<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Sapateiro de profiss\u00e3o e comunista, foi membro do PCB. Depois integrou a VPR e participou da guerrilha do Vale da Ribeira, comandada pelo capit\u00e3o Carlos Lamarca. Foi preso em maio de 1970 e saiu da pris\u00e3o em troca do embaixador da Alemanha no Brasil. Morreu no massacre da estrada de Medianeira<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">12. JOS\u00c9 RODRIGUES VIEIRA NETTO<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Da turma de 1932 da Faculdade de Direito da UFPR, alcan\u00e7ou fama de ser o melhor advogado paranaense. Catedr\u00e1tico de Direito Civil da UFPR, cassado por decreto da ditadura militar, aposentado compulsoriamente em 1964, preso pelo Ex\u00e9rcito e processado.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Eleito Deputado Estadual Constituinte em 1947 pelo Partido Comunista Brasileiro. Seu mandato parlamentar foi cassado em 1948, assim como os demais mandatos parlamentares estaduais e federais dos comunistas, ap\u00f3s o PCB ter sua legenda extirpada pelo Tribunal Superior Eleitoral, com apoio do governo federal, em 1947. Presidiu o Conselho Seccional da OAB-PR nos anos 57\/59 e 59\/61.A biografia do jurista ser\u00e1 lan\u00e7ada no dia 14 de agosto na Semana do Advogado da OAB.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">13. JURANDIR RIOS GAR\u00c7ONI<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Nascido em Araraquara, em 1942, S\u00e3o Paulo, foi estudante de Arquitetura, na UFPR, sendo eleito presidente do Diret\u00f3rio Central dos Estudantes (DCE) e, nessa condi\u00e7\u00e3o, liderou os principais movimentos estudantis daquele per\u00edodo, como a invas\u00e3o do Centro Polit\u00e9cnico, a tomada da Reitoria e passeatas. Em 1968, foi preso no Congresso da UNE em Ibi\u00fana e teve sua pris\u00e3o preventiva decretada. Em 1969 foi processado em Curitiba, juntamente com outras lideran\u00e7as estudantis e, em 1971, foi preso em S\u00e3o Paulo por sua participa\u00e7\u00e3o na organiza\u00e7\u00e3o de esquerda Pol\u00edtica Oper\u00e1ria (POLOP). Barbaramente torturado, cortou os pulsos na pris\u00e3o, em uma tentativa extrema de resistir \u00e0s torturas. Em 1984, assumiu o cargo de Curador do Patrim\u00f4nio da Secretaria de Cultura do Paran\u00e1, onde coordenou o processo de tombamento da Serra do Mar. Como resultado de seu trabalho, veio a falecer, em 1985, quando realizava um voo de estudos t\u00e9cnicos sobre a Serra da Mar. O Governo do Estado homenageou Jurandir com um monumento na Estrada da Graciosa, por ocasi\u00e3o da conclus\u00e3o do tombamento da Serra, alguns meses ap\u00f3s sua morte. No monumento, assentado sobre uma base de terra trazida especialmente de Araraquara e misturada com a terra do Paran\u00e1, uma placa assinala que \u201cJurandir escolheu essa terra como sua, aqui viveu, casou, teve seus filhos e aqui lutou\u201d. Foi casado com Cecilia Gar\u00e7oni e deixou duas filhas, Ines e Isabel Gar\u00e7oni.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">14. LAUDEMIR TURRA<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Morreu em 13 de julho de 2013, em Corb\u00e9lia, aos 82 anos, um dos \u00faltimos pioneiros do Oeste do Paran\u00e1. Membro de uma fam\u00edlia que associou seu nome \u00e0 luta de resist\u00eancia \u00e0 ditadura e, mais tarde, \u00e0 reconstru\u00e7\u00e3o democr\u00e1tica. Integrante da organiza\u00e7\u00e3o brizolista Grupo dos Onze, transferiu-se para o Oeste paranaense logo ap\u00f3s o golpe militar de 1964. Integrou ali uma gera\u00e7\u00e3o de pioneiros que ajudou a construir uma das mais pr\u00f3speras regi\u00f5es do Brasil.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Em Corb\u00e9lia, munic\u00edpio criado tr\u00eas anos antes de sua chegada \u00e0 regi\u00e3o, Laudemir organizou com os irm\u00e3os a Madeireira Turra, que se tornaria uma das maiores da regi\u00e3o. Retornou \u00e0 pol\u00edtica, filiado ao MDB. Foi prefeito em 1976 e 1988.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">15. LUIZ ANDR\u00c9 F\u00c1VERO<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Izabel F\u00e1vero &#8211; professora, e esposo, presos em 1970, em Nova Aurora (PR). Hoje, vive no Recife, onde \u00e9 docente universit\u00e1ria: \u201cEu, meu companheiro e os pais dele fomos torturados a noite toda ali, um na frente do outro. Era muito choque el\u00e9trico. Fomos literalmente saqueados. Levaram tudo o que t\u00ednhamos: as economias do meu sogro, a roupa de cama e at\u00e9 o meu enxoval. No dia seguinte, eu e meu companheiro fomos torturados pelo capit\u00e3o J\u00falio Cerd\u00e1 Mendes e pelo tenente M\u00e1rio Expedito Ostrovski. Foi pau de arara, choques el\u00e9tricos, jogo de empurrar e amea\u00e7as de estupro. Eu estava gr\u00e1vida de dois meses, e eles estavam sabendo. No quinto dia, depois de muito choque, pau de arara, amea\u00e7a de estupro e insultos, eu abortei. Quando melhorei, voltaram a me torturar\u201d.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">16. NOEL NASCIMENTO<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Filho de Sebasti\u00e3o Nascimento e Maria Claudia Bittencourt de Castro Nascimento. Formou-se em Direito em 1949, na UFPR e foi promotor de justi\u00e7a em v\u00e1rias cidades do interior do estado. Colaborou durante d\u00e9cadas em jornais e revistas com ensaios, poemas e textos liter\u00e1rios. Considerado o maior romancista do sul do pa\u00eds da era p\u00f3s \u00c9rico Ver\u00edssimo. Foi atingido pelo Ato Institucional n\u00ba 1, preso pol\u00edtico em 64 e em 75, retornando ao Minist\u00e9rio P\u00fablico na vig\u00eancia da Lei da Anistia. Tomou posse da cadeira 27 da Academia Paranaense de Letras em 1979. Em 1995 ganhou o Concurso Nacional de Romances promovido pela Secretaria de Estado da Cultura do Paran\u00e1 com \u201cArcabuzes\u201d.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">17. ONOFRE PINTO<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Ano de nascimento e filia\u00e7\u00e3o<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Era o mais procurado de todos pelo governo militar. Foi um dos fundadores da VPR e recrutou o capit\u00e3o Carlos Lamarca para essa organiza\u00e7\u00e3o. Foi preso pelos militares em mar\u00e7o de e 1969 e solto seis meses depois junto com outros 14 presos em troca do embaixador norte-americano Charles Elbrick, sequestrado em setembro de 1969 pelos guerrilheiros do MR-8. Ao contr\u00e1rio dos demais, n\u00e3o foi assassinado no Parque Nacional do Igua\u00e7u. Acabou morto cerca de dois dias depois, em Foz do Igua\u00e7u. Seu corpo foi desovado pelos militares no Rio S\u00e3o Francisco Falso, em Santa Helena. Tinha 36 anos quando foi morto.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">18. R\u00c9GINES PROCHMANN<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Militante da A\u00e7\u00e3o Popular (AP) \u2013 organiza\u00e7\u00e3o oriunda da esquerda crist\u00e3 \u2013, Reginis Prochmann foi desligado da UFPR, onde era m\u00e9dico residente, em 1964.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">19. RIAD SALAMUNI<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Opositor ao regime militar e, por sua luta em defesa da democracia, sofreu in\u00fameras persegui\u00e7\u00f5es, inclusive com a invas\u00e3o de sua resid\u00eancia para o confisco de sua biblioteca particular. Riad, que era professor e posteriormente reitor \u2013 o primeiro eleito \u2013 da UFPR, costumava abrigar em sua casa alunos que estavam sendo procurados por serem opositores ao governo militar. Membro do antigo PSB (Partido Socialista Brasileiro), defendia de forma ardorosa id\u00e9ias nacionalistas, entre as quais podemos citar o apoio dado \u00e0 campanha \u201cO petr\u00f3leo \u00e9 nosso\u201d. Era um intelectual humanista, que questionou sucessivamente o governo militar antidemocr\u00e1tico dos anos de chumbo.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">20. TEREZA URBAN<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Militou na Polop (Pol\u00edtica Oper\u00e1ria) contra a ditadura militar, tendo sido presa tr\u00eas vezes e torturada. Na d\u00e9cada de setenta, foi mandada para o ex\u00edlio no Chile.Com o fim do regime militar, a jornalista se dedicou \u00e0 causa ambiental e trabalhou em diversos ve\u00edculos, como a revista Veja e o jornal Estado de S\u00e3o Paulo. Tereza escreveu mais de vinte livros. Morreu aos 67 anos de idade, em junho passado, v\u00edtima de infarto.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">21. V\u00cdCTOR CARLOS RAMOS<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Saiu do Brasil e foi para o Uruguai ao ter sua pris\u00e3o preventiva decretada pelo Tribunal Militar. Logo ap\u00f3s, foi para o Chile. Em 1974 ingressou no grupo de Onofre Pinto e retornou clandestinamente ao Brasil, sendo logo assassinado no Parque Nacional do Igua\u00e7u com 30 anos de idade.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">22. WALFRIDO SOARES DE OLIVEIRA<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Walfrido Soares de Oliveira e os irm\u00e3os Arpad e D\u00e1rio Printz figuravam entreos primeiros e principais dirigentes das atividades comunistas no Paran\u00e1 na d\u00e9cada de1930. Eram funcion\u00e1rios da RVPSC (Rede Vi\u00e1ria Paran\u00e1-Santa Catarina) e atuaram,certamente, por mais de uma d\u00e9cada no Partido Comunista. Na segunda metade dad\u00e9cada de 1940, mais precisamente em 1945, eles eram refer\u00eancias na Dire\u00e7\u00e3oEstadual, sendo que Oliveira assumiu a dire\u00e7\u00e3o estadual e Printz, a dire\u00e7\u00e3o do Partidona capital.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">23. OTTO BRACARENSE<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Foi dirigente do Sindicado dos Banc\u00e1rios de Curitiba e Presidente da Federa\u00e7\u00e3o dos Banc\u00e1rios do Paran\u00e1 no final da d\u00e9cada de 50 e inicio da d\u00e9cada de 60. Em 1964, por ocasi\u00e3o do golpe militar, era Delegado do IAPB (Instituto de Aposentadoria e Previd\u00eancia dos Banc\u00e1rios) no Paran\u00e1. Foi preso em 1964 no antigo pres\u00eddio do AH\u00da e em 1968, no antigo Quartel do Ex\u00e9rcito na Pra\u00e7a Rui Barbosa. Pertencia ao quadro dirigente do Partido Comunista Brasileiro (PCB). Foi um dos principais articuladores da Campanha Diretas J\u00e1.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">24. WALTER ALBERTO P\u00c9COITS<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">M\u00e9dico, natural de Erechim, Rio Grande do Sul, foi uma das mais importantes figuras pol\u00edticas do sudoeste do Paran\u00e1, tendo participado ativamente na acirrada luta entre posseiros, companhias de terras e os governos estadual e federal, ocorrida em 1957 no governo de Mois\u00e9s Lupion. Conhecido como Revolta dos Posseiros, o conflito envolveu milhares de colonos e foi o principal marco hist\u00f3rico da regi\u00e3o sudoeste de Paran\u00e1, sendo considerada por muitos historiadores como o \u00fanico levante agr\u00e1rio armado vitorioso na hist\u00f3ria do Brasil. Por sua defesa dos colonos, Dr. Walter foi preso, tendo perdido um olho pelas torturas que sofreu.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Sua carreira pol\u00edtica come\u00e7ou sua cidade Natal, como vereador. Mudando-se para Francisco Beltr\u00e3o, na d\u00e9cada de 1950, foi eleito vereador, prefeito e deputado estadual. Em 1964, foi cassado pelo Regime Militar, perdendo seus direitos pol\u00edticos por 10 anos. No governo de Jos\u00e9 Richa, foi secret\u00e1rio estadual de Reforma Agr\u00e1ria, e, mais tarde, secret\u00e1rio municipal de Sa\u00fade de Francisco Beltr\u00e3o.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Fonte &#8211; Promad<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na sess\u00e3o de abertura da Caranava da Anistia, que acontecer\u00e1 na sede da OAB-PR, em Curitiba, na sexta-feira,16, haver\u00e1 homenagens p\u00f3stumas a ex-presos pol\u00edticos e seus familiares, al\u00e9m de homenagem ao ex-prefeito de Curitiba, Maur\u00edcio Fruet, e ao ex-governador, Jos\u00e9 Richa, que lutaram pela redemocratiza\u00e7\u00e3o do pa\u00eds. Veja alguns dos nomes que ser\u00e3o homenageados:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/posts\/6308"}],"collection":[{"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/comments?post=6308"}],"version-history":[{"count":0,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/posts\/6308\/revisions"}],"wp:attachment":[{"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/media?parent=6308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/categories?post=6308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/tags?post=6308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}