{"id":6429,"date":"2013-09-10T09:36:04","date_gmt":"2013-09-10T09:36:04","guid":{"rendered":"http:\/\/anistiapolitica.org.br\/abap3\/2013\/09\/10\/violacoes-cometidas-durante-o-regime-militar-serao-investigadas-em-sao-joao-de-meriti\/"},"modified":"2013-09-10T09:36:04","modified_gmt":"2013-09-10T09:36:04","slug":"violacoes-cometidas-durante-o-regime-militar-serao-investigadas-em-sao-joao-de-meriti","status":"publish","type":"post","link":"https:\/\/anistiapolitica.org.br\/abap3\/2013\/09\/10\/violacoes-cometidas-durante-o-regime-militar-serao-investigadas-em-sao-joao-de-meriti\/","title":{"rendered":"Viola\u00e7\u00f5es cometidas durante o regime militar ser\u00e3o investigadas em S\u00e3o Jo\u00e3o de Meriti"},"content":{"rendered":"<p class=\"p1\" style=\"text-align: justify;\">S\u00e3o Jo\u00e3o de Meriti est\u00e1 instalando sua Comiss\u00e3o Municipal da Verdade, iniciativa que ter\u00e1 como objetivo investigar e esclarecer as graves viola\u00e7\u00f5es de direitos humanos praticadas no munic\u00edpio durante o per\u00edodo\u00a0da\u00a0ditadura militar. Na \u00faltima quinta-feira (05\/09), profissionais\u00a0da\u00a0Secretaria Municipal de Direitos Humanos e Igualdade Racial (SEMDHIR)\u00a0\u00a0se reuniram com uma representante da Comiss\u00e3o Estadual da Verdade para acertar os \u00faltimos detalhes para a implanta\u00e7\u00e3o da Comiss\u00e3o.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\" \/><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-6428\" src=\"http:\/\/anistiapolitica.org.br\/abap3\/wp-content\/uploads\/2013\/09\/08092013000019.jpg\" border=\"0\" width=\"300\" height=\"200\" \/>  <!--more-->  <\/p>\n<p class=\"p1\" style=\"text-align: justify;\">A Lei para implanta\u00e7\u00e3o da Comiss\u00e3o Municipal da Verdade foi aprovada pela C\u00e2mara de Vereadores na \u00faltima semana. \u201cAssim que o prefeito Sandro Matos tomou conhecimento da comiss\u00e3o ele autorizou o envio para aprova\u00e7\u00e3o da C\u00e2mara. Temos no munic\u00edpio v\u00e1rias fam\u00edlias de presos, torturados e desaparecidos pol\u00edticos durante a ditadura. \u00c9 uma quest\u00e3o de justi\u00e7a levantar estas hist\u00f3rias que aconteceram em nossa cidade. Para isso queremos envolver a sociedade civil organizada\u201d, destacou Erika dos Santos, superintendente de Promo\u00e7\u00e3o e Defesa dos Direitos Humanos da SEMDHIR. Ela informou ainda que os interessados em saber sobre a Comiss\u00e3o devem procurar a Secretaria, que fica na Avenida Presidente Lincoln, 911, Edif\u00edcio Antares, sala 307, em Vilar dos Teles, ou pelo telefone (21) 2751-0204. O atendimento \u00e9 de segunda a sexta, das 9h \u00e0s 17h.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">O encontro contou tamb\u00e9m com a presen\u00e7a da assessora da Comiss\u00e3o Estadual da Verdade, Nat\u00e1lia Cindra. \u201cNosso trabalho \u00e9 promover a interioriza\u00e7\u00e3o da comiss\u00e3o, destacando munic\u00edpios que historicamente s\u00e3o importantes neste per\u00edodo. Sabemos, por exemplo, que em S\u00e3o Jo\u00e3o de Meriti havia um s\u00edtio onde houve tortura e repress\u00e3o durante a ditadura militar. Precisamos investigar onde foi este local, localizar as fam\u00edlias destas v\u00edtimas, entre outras a\u00e7\u00f5es\u201d, completou Nat\u00e1lia.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">\u00a0<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Fonte &#8211; Baixada F\u00e1cil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e3o Jo\u00e3o de Meriti est\u00e1 instalando sua Comiss\u00e3o Municipal da Verdade, iniciativa que ter\u00e1 como objetivo investigar e esclarecer as graves viola\u00e7\u00f5es de direitos humanos praticadas no munic\u00edpio durante o per\u00edodo\u00a0da\u00a0ditadura militar. Na \u00faltima quinta-feira (05\/09), profissionais\u00a0da\u00a0Secretaria Municipal de Direitos Humanos e Igualdade Racial (SEMDHIR)\u00a0\u00a0se reuniram com uma representante da Comiss\u00e3o Estadual da Verdade para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6428,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/posts\/6429"}],"collection":[{"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/comments?post=6429"}],"version-history":[{"count":0,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/posts\/6429\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/media\/6428"}],"wp:attachment":[{"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/media?parent=6429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/categories?post=6429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anistiapolitica.org.br\/abap3\/wp-json\/wp\/v2\/tags?post=6429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}